{"id":174,"count":1,"description":"Entdecken Sie die Magie Indonesiens mit einer The Planet-Tour. Erleben Sie idyllische Str\u00e4nde, atemberaubende Vulkane und pulsierende Kulturen an Orten wie Lombok und den Gili-Inseln. Tauchen Sie ein in das Herz des Archipels und schaffen Sie unvergessliche Erinnerungen!","link":"https:\/\/theplanet.es\/de\/experiencia\/indonesia\/","name":"Indonesien","slug":"indonesien","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/theplanet.es\/de\/wp-json\/wp\/v2\/categories\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplanet.es\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/theplanet.es\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/theplanet.es\/de\/wp-json\/wp\/v2\/posts?categories=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}