{"id":41,"count":3,"description":"Entdecken Sie mit The Planet die Magie Finnlands. Erleben Sie ein unvergessliches nordisches Abenteuer \u2013 von den Nordlichtern in Lappland bis ins moderne Helsinki. Entdecken Sie W\u00e4lder, Seen und die faszinierende finnische Kultur!","link":"https:\/\/theplanet.es\/de\/experiencia\/finlandia\/","name":"Finnland","slug":"finnland","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/theplanet.es\/de\/wp-json\/wp\/v2\/categories\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theplanet.es\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/theplanet.es\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/theplanet.es\/de\/wp-json\/wp\/v2\/posts?categories=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}